{"id":367,"count":7,"description":"","link":"https:\/\/elainnovation.com\/es\/categoria-producto\/gama-de-mallas\/","name":"Gama de mallas","slug":"gama-de-mallas","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Gama de mallas - ELA Innovation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elainnovation.com\/es\/categoria-producto\/gama-de-mallas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Gama de mallas - ELA Innovation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elainnovation.com\/es\/categoria-producto\/gama-de-mallas\/\" \/>\n<meta property=\"og:site_name\" content=\"ELA Innovation\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ElaInnovation\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/elainnovation.com\\\/es\\\/categoria-producto\\\/gama-de-mallas\\\/\",\"url\":\"https:\\\/\\\/elainnovation.com\\\/es\\\/categoria-producto\\\/gama-de-mallas\\\/\",\"name\":\"Archives des Gama de mallas - ELA Innovation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elainnovation.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elainnovation.com\\\/es\\\/categoria-producto\\\/gama-de-mallas\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elainnovation.com\\\/es\\\/categoria-producto\\\/gama-de-mallas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elainnovation.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gama de mallas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elainnovation.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/elainnovation.com\\\/es\\\/\",\"name\":\"ELA Innovation\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/elainnovation.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elainnovation.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elainnovation.com\\\/es\\\/#organization\",\"name\":\"ELA Innovation\",\"url\":\"https:\\\/\\\/elainnovation.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elainnovation.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elainnovation.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/LOGO-Ela-Innovation.png\",\"contentUrl\":\"https:\\\/\\\/elainnovation.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/LOGO-Ela-Innovation.png\",\"width\":436,\"height\":240,\"caption\":\"ELA Innovation\"},\"image\":{\"@id\":\"https:\\\/\\\/elainnovation.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ELA-Innovation-489302644542142\\\/\",\"https:\\\/\\\/x.com\\\/ElaInnovation\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/elainnovation\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Gama de mallas - ELA Innovation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elainnovation.com\/es\/categoria-producto\/gama-de-mallas\/","og_locale":"es_ES","og_type":"article","og_title":"Archives des Gama de mallas - ELA Innovation","og_url":"https:\/\/elainnovation.com\/es\/categoria-producto\/gama-de-mallas\/","og_site_name":"ELA Innovation","twitter_card":"summary_large_image","twitter_site":"@ElaInnovation","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/elainnovation.com\/es\/categoria-producto\/gama-de-mallas\/","url":"https:\/\/elainnovation.com\/es\/categoria-producto\/gama-de-mallas\/","name":"Archives des Gama de mallas - ELA Innovation","isPartOf":{"@id":"https:\/\/elainnovation.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/elainnovation.com\/es\/categoria-producto\/gama-de-mallas\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/elainnovation.com\/es\/categoria-producto\/gama-de-mallas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elainnovation.com\/es\/"},{"@type":"ListItem","position":2,"name":"Gama de mallas"}]},{"@type":"WebSite","@id":"https:\/\/elainnovation.com\/es\/#website","url":"https:\/\/elainnovation.com\/es\/","name":"ELA Innovation","description":"","publisher":{"@id":"https:\/\/elainnovation.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elainnovation.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elainnovation.com\/es\/#organization","name":"ELA Innovation","url":"https:\/\/elainnovation.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elainnovation.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/elainnovation.com\/wp-content\/uploads\/2020\/07\/LOGO-Ela-Innovation.png","contentUrl":"https:\/\/elainnovation.com\/wp-content\/uploads\/2020\/07\/LOGO-Ela-Innovation.png","width":436,"height":240,"caption":"ELA Innovation"},"image":{"@id":"https:\/\/elainnovation.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ELA-Innovation-489302644542142\/","https:\/\/x.com\/ElaInnovation","https:\/\/www.linkedin.com\/company\/elainnovation\/"]}]}},"_links":{"self":[{"href":"https:\/\/elainnovation.com\/es\/wp-json\/wp\/v2\/product_cat\/367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elainnovation.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/elainnovation.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/elainnovation.com\/es\/wp-json\/wp\/v2\/product?product_cat=367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}